{"id":5416,"date":"2022-01-14T08:56:59","date_gmt":"2022-01-14T07:56:59","guid":{"rendered":"https:\/\/ffl.lu\/2022\/01\/die-lepra-und-ihre-geister\/"},"modified":"2022-01-14T08:57:00","modified_gmt":"2022-01-14T07:57:00","slug":"die-lepra-und-ihre-geister","status":"publish","type":"post","link":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/","title":{"rendered":"Die Lepra und ihre Geister\u2026"},"content":{"rendered":"\n<p>Lepra ist eine chronische Infektionskrankheit, die durch Bakterien mit dem Namen \u201eMycobacterium leprae\u201c hervorgerufen wird und vor allem die Haut, die peripheren Nerven, die Schleimhaut der oberen Atemwege sowie die Augen bef\u00e4llt und besch\u00e4digt. Neben Lepra geh\u00f6ren auch Buruli-Ulkus und die Framb\u00f6sie, die sich allesamt auf der Haut manifestieren, zur Gruppe der vernachl\u00e4ssigten Tropenkrankheiten (NTDs). &#13;\n<\/p>\n\n<p>Innerhalb der letzten 20 Jahre konnten aufgrund eines einfacheren Zugangs zu medizinischer Behandlung und Pflege ganze 12 Millionen an Lepra erkrankte Menschen behandelt werden. Die chronische Infektionskrankheit konnte zudem aus 108 von 122 L\u00e4ndern, in denen sie zuvor noch eine gesundheitliche Notlage dargestellt hatte, ausgerottet werden. <\/p>\n\n<p>Doch diese Krankheit, von der gesagt wird, dass sie \u201ean der Haut leckt und an den Nerven nagt\u201c, betrifft immer noch mehr als 3 Millionen Menschen auf der ganzen Welt. Zudem soll sich alle 2 Minuten eine weitere Person daran infizieren. Ein wichtiger Faktor, der bei der Verbreitung von Lepra beitr\u00e4gt, ist ihre Inkubationszeit, die im Durchschnitt 5 Jahre betr\u00e4gt und bis zu ganzen 20 andauern kann. &#13;\n<\/p>\n\n<p>Das bedeutet, dass es sehr lange dauert, bis sich die ersten Symptome bemerkbar machen. Indessen m\u00f6gen sich bei der infizierten Person zwar keine Krankheitszeichen bemerkbar machen, nichtsdestotrotz bleibt Ansteckungsgefahr.<\/p>\n\n<p>Neben den gesundheitlichen Problemen gibt es einen weiteren Aspekt, der die Bek\u00e4mpfung von Lepra, die bereits nachweislich im Mittelalter existiert hat, gleichzeitig zum Kampf gegen Ausgrenzung macht: Die infizierten Menschen werden nicht nur von ihren Familien, sondern auch von der gesamten Gesellschaft versto\u00dfen. Das ist auch heute noch der Fall, selbst wenn die Menschen die Krankheit \u00fcberlebt haben und geheilt sind.&#13;\n&#13;\n<strong>Ein sehr eindr\u00fcckliches Beispiel hierf\u00fcr ist das Dorf Kp\u00e9l\u00e9 Tutu in Togo, das zur Pr\u00e4fektur Kp\u00e9l\u00e9 (Region des Plateaux) geh\u00f6rt. Dieses Dorf stellte lange Zeit f\u00fcr viele von Lepra betroffenen Personen und deren Familien einen isolierten R\u00fcckzugsort dar, wo sie von den umliegenden Gemeinden v\u00f6llig ausgeschlossen lebten. Obwohl in der Zwischenzeit Jahrzehnte vergangen sind und ein Gesundheitszentrum erbaut worden ist, bleibt dieses leprafreie Dorf bis heute bestehen und wird nach wie vor von den gleichen Familien und deren Nachkommen abseits der umliegenden Bev\u00f6lkerung bestehen. Sie leben in der gleichen Gesellschaft und sind v\u00f6llig von den umliegenden Gemeinden isoliert<\/strong>.<\/p>\n\n<p>Lepra und ihre Symptome schlie\u00dfen die Betroffenen aus und ihre Geister verfolgen die Geheilten weitergehend\u2026<\/p>\n\n<p>Lepra und vernachl\u00e4ssigte Tropenkrankheiten allgemein werden oft als Krankheiten der Armut und der Promiskuit\u00e4t angesehen. Dabei wird vergessen, dass es sich in erster Linie um Krankheiten der Abgeschiedenheit handelt: Der Abgeschiedenheit sowohl von Gesundheitszentren als auch des Zugangs zu medizinischer Versorgung. &#13;\n&#13;\n<\/p>\n\n<p>Lebt man in unseren Partner- und Einsatzl\u00e4ndern weit von den Gesundheitseinrichtungen entfernt, so kommt es nicht selten vor, dass man kilometerweit laufen muss, um eine einfach \u00e4rztliche Untersuchung zu erhalten. Unser Ziel besteht darin, dazu beizutragen, derartige sanit\u00e4re W\u00fcsten in Zukunft zu verhindern. Unsere Projekte haben jedoch auch einen pr\u00e4ventiven Ansatz, damit die ben\u00f6tigten Informationen an die Bev\u00f6lkerung dringen k\u00f6nnen und diese somit die Verantwortung f\u00fcr ihre eigene Gesundheit \u00fcbernehmen kann. <\/p>\n\n<p>Lepra ist genauso wenig wie Buruli-Ulkus, die Framb\u00f6sie und andere NTDs nicht ausgerottet worden. Deshalb werden wir uns auch im Jahr 2022 weiterhin f\u00fcr deren Bek\u00e4mpfung einsetzen. &#13;\n<\/p>\n\n<p>Lara Beauguerlange&#13;\nBeauftragte f\u00fcr Sponsoring und Partnerschaf&#13;\n&#13;\nmecenat@ffl.lu<\/p>\n\n<h2 class=\"wp-block-heading\">Erfahrungsbericht <\/h2>\n\n<p>Kaddi Kpanou, Leiter der R-FFL  &#8211; Benin<\/p>\n\n<p><em>Die Angst vor Lepra h\u00e4lt aufgrund der Folgesch\u00e4den, die sie verursacht, an. <\/em><\/p>\n\n<p><strong>Welche Behandlungsmethoden gibt es in den D\u00f6rfern, wenn die Gesundheitszentren zu weit entfernt sind? <\/strong><\/p>\n\n<p>Die Selbstmedikation, die Verwendung von Heilpflanzen Tchayo, Wontonzonzouin oder Togbe sowie die Behandlung von Traditherapeuten.&#13;\n<\/p>\n\n<p><strong>Wird sich in einem Dorf gegenseitig bei der Pflege von Menschen geholfen?<\/strong><\/p>\n\n<p>Die Familien, die die Betroffenen begleiten, f\u00fchlen sich oft zur\u00fcckgewiesen oder ausgegrenzt. Die gegenseitige Hilfe ist relativ und zeitlich begrenzt. Sie variiert auch von einer Gemeinde zur anderen, je nachdem, wie lange die Genesung dauert.<\/p>\n\n<p><strong>Wie verl\u00e4uft der Genesungsprozess?<\/strong><\/p>\n\n<p>Der Genesungsprozess ist aus psychologischer Sicht aufgrund der sozialen Wiedereingliederung belastend. Nach der Behandlung und Heilung wird der Patient aus der Pflegeeinrichtung entlassen und kann in seine Wohnung zur\u00fcckkehren. Er wird dann sp\u00e4ter bei bestimmten Feldaktivit\u00e4ten (NTD-SCREENUNG, Aufkl\u00e4rung, \u00dcberwachung der dezentralen Standorte) in den betroffenen D\u00f6rfern weiter betreut. <\/p>\n\n<p><strong>Wie l\u00e4uft eine Aufkl\u00e4rungsveranstaltung \u00fcber NTDs ab?<\/strong><\/p>\n\n<ul class=\"wp-block-list\"><li>Die Aktivit\u00e4t wird anhand eines Briefings der Akteure vor Ort gestartet (\u00f6ffentlicher Ausrufer, Gemeinschaftsrelais, Dorfvorstehern, Personal von CDTUB Allada und Gemeindegesundheitszentrum) die zum Thema NTDs mit Hautmanifestation vorbereitet werden. &#13;\n&#13;\n<\/li><li>Die Aufkl\u00e4rungssitzungen werden durch ein genau festgelegtes Programm gem\u00e4\u00df den identifizierten D\u00f6rfern mit genauer Angabe der Startzeit geplant.  &#13;\n<\/li><li>Umsetzung der Planung <\/li><li>W\u00e4hrend der Aktivit\u00e4t findet ein interaktiver Austausch \u00fcber hautmanifestierende NTDs im Allgemeinen mit Schwerpunkt auf Lepra, Buruli-Ulkus und Framb\u00f6sie statt; Verwendung von Bilderboxen und audio-visuellen Medien Der Austausch endet einerseits mit Fragen und Antworten und andererseits mit der Demonstration, wie sich verhalten werden sollte, falls eine verd\u00e4chtige L\u00e4sion, die auf NTDs mit Hautmanifestation hinweist, entdeckt wird.<\/li><\/ul>\n<p><strong>Wie reagieren die Dorfbewohner w\u00e4hrend der Sitzungen?<\/strong><\/p>\n\n<p>Die Dorfbewohner sind w\u00e4hrend der Aktivit\u00e4ten aufnahmebereit, berichten von ihren eigenen Erlebnissen und stellen Fragen, um ein besseres Verst\u00e4ndnis zu erreichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lepra ist eine chronische Infektionskrankheit, die durch Bakterien mit dem Namen \u201eMycobacterium leprae\u201c hervorgerufen wird und vor allem die Haut, die peripheren Nerven, die Schleimhaut der oberen Atemwege sowie die [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":5413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39],"tags":[1213,1097,1212,1106],"class_list":["post-5416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-gesundheit-de","tag-gesundheit","tag-lepra","tag-non-classifiee-de-5"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Lepra und ihre Geister\u2026 - Fondation Follereau Luxembourg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Lepra und ihre Geister\u2026 - Fondation Follereau Luxembourg\" \/>\n<meta property=\"og:description\" content=\"Lepra ist eine chronische Infektionskrankheit, die durch Bakterien mit dem Namen \u201eMycobacterium leprae\u201c hervorgerufen wird und vor allem die Haut, die peripheren Nerven, die Schleimhaut der oberen Atemwege sowie die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Follereau Luxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-14T07:56:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-14T07:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3605\" \/>\n\t<meta property=\"og:image:height\" content=\"3604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gregory Monaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gregory Monaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/\"},\"author\":{\"name\":\"Gregory Monaco\",\"@id\":\"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265\"},\"headline\":\"Die Lepra und ihre Geister\u2026\",\"datePublished\":\"2022-01-14T07:56:59+00:00\",\"dateModified\":\"2022-01-14T07:57:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/\"},\"wordCount\":867,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg\",\"keywords\":[\"Gesundheit\",\"Gesundheit\",\"Lepra\",\"Non classifi\u00e9(e)\"],\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/\",\"url\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/\",\"name\":\"Die Lepra und ihre Geister\u2026 - Fondation Follereau Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/ffl.lu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg\",\"datePublished\":\"2022-01-14T07:56:59+00:00\",\"dateModified\":\"2022-01-14T07:57:00+00:00\",\"author\":{\"@id\":\"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265\"},\"breadcrumb\":{\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage\",\"url\":\"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg\",\"contentUrl\":\"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg\",\"width\":3605,\"height\":3604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ffl.lu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Lepra und ihre Geister\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ffl.lu\/de\/#website\",\"url\":\"https:\/\/ffl.lu\/de\/\",\"name\":\"Fondation Follereau Luxembourg\",\"description\":\"Tout seul, on va vite. Ensemble, on va plus loin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ffl.lu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265\",\"name\":\"Gregory Monaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/ffl.lu\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g\",\"caption\":\"Gregory Monaco\"},\"url\":\"https:\/\/ffl.lu\/de\/author\/gregory\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Lepra und ihre Geister\u2026 - Fondation Follereau Luxembourg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/","og_locale":"de_DE","og_type":"article","og_title":"Die Lepra und ihre Geister\u2026 - Fondation Follereau Luxembourg","og_description":"Lepra ist eine chronische Infektionskrankheit, die durch Bakterien mit dem Namen \u201eMycobacterium leprae\u201c hervorgerufen wird und vor allem die Haut, die peripheren Nerven, die Schleimhaut der oberen Atemwege sowie die [&hellip;]","og_url":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/","og_site_name":"Fondation Follereau Luxembourg","article_published_time":"2022-01-14T07:56:59+00:00","article_modified_time":"2022-01-14T07:57:00+00:00","og_image":[{"width":3605,"height":3604,"url":"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg","type":"image\/jpeg"}],"author":"Gregory Monaco","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gregory Monaco","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#article","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/"},"author":{"name":"Gregory Monaco","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265"},"headline":"Die Lepra und ihre Geister\u2026","datePublished":"2022-01-14T07:56:59+00:00","dateModified":"2022-01-14T07:57:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/"},"wordCount":867,"commentCount":0,"image":{"@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg","keywords":["Gesundheit","Gesundheit","Lepra","Non classifi\u00e9(e)"],"articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/","url":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/","name":"Die Lepra und ihre Geister\u2026 - Fondation Follereau Luxembourg","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage"},"image":{"@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg","datePublished":"2022-01-14T07:56:59+00:00","dateModified":"2022-01-14T07:57:00+00:00","author":{"@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265"},"breadcrumb":{"@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#primaryimage","url":"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg","contentUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2022\/01\/967V0239_RJ-copie-2.jpg","width":3605,"height":3604},{"@type":"BreadcrumbList","@id":"https:\/\/ffl.lu\/de\/2022\/01\/die-lepra-und-ihre-geister\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ffl.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Die Lepra und ihre Geister\u2026"}]},{"@type":"WebSite","@id":"https:\/\/ffl.lu\/de\/#website","url":"https:\/\/ffl.lu\/de\/","name":"Fondation Follereau Luxembourg","description":"Tout seul, on va vite. Ensemble, on va plus loin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ffl.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265","name":"Gregory Monaco","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g","caption":"Gregory Monaco"},"url":"https:\/\/ffl.lu\/de\/author\/gregory\/"}]}},"_links":{"self":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/5416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/comments?post=5416"}],"version-history":[{"count":1,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/5416\/revisions"}],"predecessor-version":[{"id":5417,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/5416\/revisions\/5417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media\/5413"}],"wp:attachment":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media?parent=5416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/categories?post=5416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/tags?post=5416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}