{"id":5179,"date":"2021-10-20T08:27:39","date_gmt":"2021-10-20T06:27:39","guid":{"rendered":"https:\/\/ffl.lu\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/"},"modified":"2021-12-06T11:01:01","modified_gmt":"2021-12-06T10:01:01","slug":"fundraising-eine-gegenseitige-bereicherung","status":"publish","type":"post","link":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/","title":{"rendered":"Fundraising: eine gegenseitige Bereicherung"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ein Fundraiser ist ein wichtiges Mitglied einer Entwicklungszusammenarbeit-NGO. Er oder sie ist aufmerksam und sucht st\u00e4ndig nach vertrauensw\u00fcrdigen Unternehmen, die die Stiftung und ihre Projekte <strong>mit bedeutenden einmaligen und\/oder regelm\u00e4\u00dfigen Mitteln unterst\u00fctzen wollen<\/strong>. Entschlossen sucht er nach potenziellen &#8222;Schirmherren&#8220;, um diese neuen Partnerschaften zu initiieren. Doch so einfach ist es nicht, denn bevor eine finanzielle Sponsoring-Partnerschaft zustande kommt, m\u00fcssen viele T\u00fcren ge\u00f6ffnet werden, die nicht selten verschlossen bleiben.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Und ausnahmsweise hat sich eine T\u00fcr f\u00fcr uns ge\u00f6ffnet, ohne dass wir \u00fcberhaupt anklopfen mussten.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Und, in der Tat kann finanzielles Sponsoring auch Teil eines <strong>proaktiven Ansatzes<\/strong> seitens der Unternehmen selbst sein. Dies ist der Fall bei einer Organisation, die aus dem Anliegen heraus, der Gesellschaft im weitesten Sinne etwas zur\u00fcckgeben zu wollen, <strong>spontan mit uns Kontakt aufgenommen hat<\/strong>, um im Jahr 2021 eine Spende zu machen&#8230;<\/p>\n\n<p class=\"wp-block-paragraph\">Bei dieser Organisation handelt es sich um LU-CIX, den Luxembourg Internet Exchange Hub. Seine Hauptaufgabe besteht darin, <strong>die Internetakteure vor Ort miteinander zu verbinden<\/strong> (nationaler und internationaler Internetzugang und\/oder Anbieter von Inhalten wie Video-Streaming-Dienste, Homebanking, soziale Netzwerke usw.).\u00a0 LU-CIX spielt aber auch eine wichtige Rolle bei der F\u00f6rderung der ICT-Akteure der Gro\u00dfregion auf internationaler Ebene.<\/p>\n\n<p class=\"wp-block-paragraph\">Auf den ersten Blick scheint dies weit von den Aktivit\u00e4ten der Stiftung abzuweichen. LU-CIX ist jedoch interessiert daran, regelm\u00e4\u00dfig zu sozialen Projekten beizutragen, insbesondere im<strong> Bildungsbereich<\/strong>. LU-CIX hat uns im September 2021 spontan kontaktiert, um uns mitzuteilen, dass sie unser Projekt &#8222;Kampf gegen den Kinderhandel im Norden Benins&#8220; unterst\u00fctzen m\u00f6chten. Dieses Projekt bezieht sich auf die Bereiche Schutz und Bildung und hat zum Ziel, zur F\u00f6rderung eines sch\u00fctzenden Umfelds beizutragen, in dem die Rechte der Kinder im Norden Benins St\u00e4rkung finden, indem alle Akteure der Gemeinschaft f\u00fcr den<strong> Schutz der Kinder<\/strong> und gegen Ausbeutung in all ihren Formen sowie f\u00fcr die Bildung der Kinder und die nachhaltige Unterst\u00fctzung von Familien <strong>in prek\u00e4ren Situationen sensibilisiert werden<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">LU-CIX hat sich nat\u00fcrlich auch f\u00fcr unser Projekt &#8222;Mind the Gap&#8220; interessiert, das dazu beitr\u00e4gt, die <strong>digitale Kluft<\/strong> in Benin und Togo zu verringern, indem es die von unseren luxemburgischen Partnern gespendeten Computer an unsere lokalen Partner in Benin und Togo schickt, die f\u00fcr die Auswahl der Schulen und die Programmierung, Verteilung und Installation der Ger\u00e4te vor Ort verantwortlich sind. In der gemeinsamen Diskussion \u00fcber dieses Projekt haben wir eine neue M\u00f6glichkeit der Zusammenarbeit erkannt, mit der M\u00f6glichkeit, dieses Projekt den Teilnehmern der Veranstaltung &#8222;Luxembourg Internet Days&#8220; zu pr\u00e4sentieren, indem wir unseren Bedarf an technischem und finanziellem Sponsoring hervorheben.<\/p>\n\n<p class=\"wp-block-paragraph\">LU-CIX hatte durch seinen vorausschauenden Ansatz die M\u00f6glichkeit, die bestehenden Angebote zu analysieren, bevor die Finanzierungsentscheidung getroffen wurde, und den Interventionsbereich bzw. das Projekt f\u00fcr 2021 zu w\u00e4hlen, der bzw. das am besten zu seinem Konzept passte.<\/p>\n\n<p class=\"wp-block-paragraph\">So konnten dank LU-CIX zwei Projekte gef\u00f6rdert werden, darunter eines in einem gezielten Teilbereich und das am besten auf die Technologie ausgerichtete Projekt, wof\u00fcr wir dem gesamten Team f\u00fcr die Unterst\u00fctzung der Stiftung herzlich danken m\u00f6chten. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Fundraiser ist ein wichtiges Mitglied einer Entwicklungszusammenarbeit-NGO. Er oder sie ist aufmerksam und sucht st\u00e4ndig nach vertrauensw\u00fcrdigen Unternehmen, die die Stiftung und ihre Projekte mit bedeutenden einmaligen und\/oder regelm\u00e4\u00dfigen [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":5176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39],"tags":[598,1210,1209,1208,600,1137,1088,568,1093,1211],"class_list":["post-5179","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-benin-de","tag-bildung-de","tag-fundraiser-de","tag-kinder-de","tag-mind-the-gap-de","tag-non-classifiee-de-16","tag-non-classifiee-de","tag-protection-de","tag-solidaritat","tag-spenden"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fundraising: eine gegenseitige Bereicherung - Fondation Follereau Luxembourg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundraising: eine gegenseitige Bereicherung - Fondation Follereau Luxembourg\" \/>\n<meta property=\"og:description\" content=\"Ein Fundraiser ist ein wichtiges Mitglied einer Entwicklungszusammenarbeit-NGO. Er oder sie ist aufmerksam und sucht st\u00e4ndig nach vertrauensw\u00fcrdigen Unternehmen, die die Stiftung und ihre Projekte mit bedeutenden einmaligen und\/oder regelm\u00e4\u00dfigen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Follereau Luxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-20T06:27:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-06T10:01:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ffl.lu\/wp-content\/uploads\/2021\/10\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gregory Monaco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gregory Monaco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/\"},\"author\":{\"name\":\"Gregory Monaco\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/f8c6c067ac1e4cfa1c1f45bdce0fa265\"},\"headline\":\"Fundraising: eine gegenseitige Bereicherung\",\"datePublished\":\"2021-10-20T06:27:39+00:00\",\"dateModified\":\"2021-12-06T10:01:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/\"},\"wordCount\":520,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg\",\"keywords\":[\"Benin\",\"Bildung\",\"fundraiser\",\"Kinder\",\"Mind The Gap\",\"Non classifi\u00e9(e)\",\"Non classifi\u00e9(e)\",\"protection\",\"Solidarit\u00e4t\",\"Spenden\"],\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/\",\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/\",\"name\":\"Fundraising: eine gegenseitige Bereicherung - Fondation Follereau Luxembourg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg\",\"datePublished\":\"2021-10-20T06:27:39+00:00\",\"dateModified\":\"2021-12-06T10:01:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/f8c6c067ac1e4cfa1c1f45bdce0fa265\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg\",\"contentUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg\",\"width\":1500,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2021\\\/10\\\/fundraising-eine-gegenseitige-bereicherung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ffl.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundraising: eine gegenseitige Bereicherung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/\",\"name\":\"Fondation Follereau Luxembourg\",\"description\":\"Tout seul, on va vite. Ensemble, on va plus loin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ffl.lu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/f8c6c067ac1e4cfa1c1f45bdce0fa265\",\"name\":\"Gregory Monaco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g\",\"caption\":\"Gregory Monaco\"},\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/author\\\/gregory\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundraising: eine gegenseitige Bereicherung - Fondation Follereau Luxembourg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/","og_locale":"de_DE","og_type":"article","og_title":"Fundraising: eine gegenseitige Bereicherung - Fondation Follereau Luxembourg","og_description":"Ein Fundraiser ist ein wichtiges Mitglied einer Entwicklungszusammenarbeit-NGO. Er oder sie ist aufmerksam und sucht st\u00e4ndig nach vertrauensw\u00fcrdigen Unternehmen, die die Stiftung und ihre Projekte mit bedeutenden einmaligen und\/oder regelm\u00e4\u00dfigen [&hellip;]","og_url":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/","og_site_name":"Fondation Follereau Luxembourg","article_published_time":"2021-10-20T06:27:39+00:00","article_modified_time":"2021-12-06T10:01:01+00:00","og_image":[{"width":1500,"height":2000,"url":"https:\/\/ffl.lu\/wp-content\/uploads\/2021\/10\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg","type":"image\/jpeg"}],"author":"Gregory Monaco","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gregory Monaco","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/#article","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/"},"author":{"name":"Gregory Monaco","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265"},"headline":"Fundraising: eine gegenseitige Bereicherung","datePublished":"2021-10-20T06:27:39+00:00","dateModified":"2021-12-06T10:01:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/"},"wordCount":520,"commentCount":0,"image":{"@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2021\/10\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg","keywords":["Benin","Bildung","fundraiser","Kinder","Mind The Gap","Non classifi\u00e9(e)","Non classifi\u00e9(e)","protection","Solidarit\u00e4t","Spenden"],"articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/","url":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/","name":"Fundraising: eine gegenseitige Bereicherung - Fondation Follereau Luxembourg","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/#primaryimage"},"image":{"@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2021\/10\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg","datePublished":"2021-10-20T06:27:39+00:00","dateModified":"2021-12-06T10:01:01+00:00","author":{"@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265"},"breadcrumb":{"@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/#primaryimage","url":"https:\/\/ffl.lu\/wp-content\/uploads\/2021\/10\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg","contentUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2021\/10\/IMG_20210326_103950_resized_20210505_055338240-e1634305339786.jpg","width":1500,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/ffl.lu\/de\/2021\/10\/fundraising-eine-gegenseitige-bereicherung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ffl.lu\/de\/"},{"@type":"ListItem","position":2,"name":"Fundraising: eine gegenseitige Bereicherung"}]},{"@type":"WebSite","@id":"https:\/\/ffl.lu\/de\/#website","url":"https:\/\/ffl.lu\/de\/","name":"Fondation Follereau Luxembourg","description":"Tout seul, on va vite. Ensemble, on va plus loin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ffl.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/f8c6c067ac1e4cfa1c1f45bdce0fa265","name":"Gregory Monaco","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1841e6c5998c6d32ef56c02dfab23342b95390ed7738f4cac6603f7e1774161a?s=96&d=mm&r=g","caption":"Gregory Monaco"},"url":"https:\/\/ffl.lu\/de\/author\/gregory\/"}]}},"_links":{"self":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/5179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/comments?post=5179"}],"version-history":[{"count":6,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/5179\/revisions"}],"predecessor-version":[{"id":5398,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/5179\/revisions\/5398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media\/5176"}],"wp:attachment":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media?parent=5179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/categories?post=5179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/tags?post=5179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}