{"id":3742,"date":"2013-09-09T00:00:00","date_gmt":"2013-09-09T00:00:00","guid":{"rendered":"https:\/\/www.ffl.lu\/2013\/09\/urgemali\/"},"modified":"2020-06-26T13:45:34","modified_gmt":"2020-06-26T13:45:34","slug":"urgemali","status":"publish","type":"post","link":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/","title":{"rendered":"URGEMALI"},"content":{"rendered":"<p><!--:fr--><\/p>\n<p style=\"text-align: justify;\"><strong>Der 19. August wurde zum allerersten Mal als Welttag der humanit\u00e4ren Hilfe begangen. Dieses Ereignis, das damals durch die internationalen Nachrichten vollauf gerechtfertigt war, war f\u00fcr alle eine Gelegenheit, sich der immensen humanit\u00e4ren Bed\u00fcrfnisse weltweit bewusst zu werden, aber auch zum Nachdenken \u00fcber Form und Methoden dieser Art von Hilfe anzuregen. Denn schnelle Hilfe sollte sich nicht auf eilige Hilfe reimen.<\/strong><\/p>\n<p style=\"text-align: justify;\">W\u00e4hrend die humanit\u00e4re Hilfe notwendigerweise eine gro\u00dfe Reaktionsf\u00e4higkeit der multilateralen Organisationen und der NGOs, die sie durchf\u00fchren, voraussetzt, sollten wir in der Tat den Teil der Menschlichkeit nicht vernachl\u00e4ssigen, der die Wurzel aller Hilfe sein sollte. Trotz der kollektiven Krise, von der die Opfer im Falle von Konflikten, Naturkatastrophen oder anderen Katastrophen betroffen sind, richtet sich die Hilfe in erster Linie an Personen, die trotz ihrer prek\u00e4ren Lage wie alle anderen durch ihre Kultur, Ethnie, Religion, ihr Geschlecht, aber auch durch ihren Geschmack und ihre Vorlieben gepr\u00e4gt sind. Und hierin liegt die Herausforderung der humanit\u00e4ren Hilfe: schnell zum Wohle der Massengruppen zu intervenieren und gleichzeitig die besondere Aufmerksamkeit, die jedem Menschen zuteil werden muss, aufrechtzuerhalten.<\/p>\n<p><!--:--><!--:de--><\/p>\n<p><!--:--><\/p>\n\n\n<div class=\"wp-block-ffl-blocks-gallery\" data-slider=\"true\" data-lightbox=\"true\"><div class=\"wrapper\"><div class=\"wp-block-ffl-blocks-gallery__holder slider__holder\"><ul class=\"wp-block-ffl-blocks-gallery__track slider__track\"><li class=\"slider__item\"><div class=\"wp-block-ffl-blocks-gallery__image\"><figure style=\"background-image:url(https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali4.jpg)\" data-lightbox-src=\"https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali4.jpg\"><figcaption><\/figcaption><\/figure><\/div><\/li><li class=\"slider__item\"><div class=\"wp-block-ffl-blocks-gallery__image\"><figure style=\"background-image:url(https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg)\" data-lightbox-src=\"https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg\"><figcaption><\/figcaption><\/figure><\/div><\/li><li class=\"slider__item\"><div class=\"wp-block-ffl-blocks-gallery__image\"><figure style=\"background-image:url(https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali2.jpg)\" data-lightbox-src=\"https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali2.jpg\"><figcaption><\/figcaption><\/figure><\/div><\/li><li class=\"slider__item\"><div class=\"wp-block-ffl-blocks-gallery__image\"><figure style=\"background-image:url(https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali1.jpg)\" data-lightbox-src=\"https:\/\/www.ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali1.jpg\"><figcaption><\/figcaption><\/figure><\/div><\/li><\/ul><\/div><button class=\"next-btn gold\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17.24\" height=\"11.54\" viewbox=\"0 0 17.24 11.54\"><path id=\"Path_255\" data-name=\"Path 255\" d=\"M-71.169,28.771l-5.968,7.157-5.969-7.16a1.5,1.5,0,0,0-2.112-.191,1.5,1.5,0,0,0-.191,2.113l7.067,8.478a1.464,1.464,0,0,0,.24.259,1.491,1.491,0,0,0,.826.341c.046,0,.093,0,.139,0s.093,0,.139,0a1.5,1.5,0,0,0,.826-.341,1.536,1.536,0,0,0,.242-.263l7.065-8.474a1.5,1.5,0,0,0-.191-2.11A1.5,1.5,0,0,0-71.169,28.771Z\" transform=\"translate(85.757 -28.23)\" fill=\"#fff\"><\/path><\/svg><\/button><button class=\"prev-btn gold\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17.24\" height=\"11.54\" viewbox=\"0 0 17.24 11.54\"><path id=\"Path_255\" data-name=\"Path 255\" d=\"M-71.169,28.771l-5.968,7.157-5.969-7.16a1.5,1.5,0,0,0-2.112-.191,1.5,1.5,0,0,0-.191,2.113l7.067,8.478a1.464,1.464,0,0,0,.24.259,1.491,1.491,0,0,0,.826.341c.046,0,.093,0,.139,0s.093,0,.139,0a1.5,1.5,0,0,0,.826-.341,1.536,1.536,0,0,0,.242-.263l7.065-8.474a1.5,1.5,0,0,0-.191-2.11A1.5,1.5,0,0,0-71.169,28.771Z\" transform=\"translate(85.757 -28.23)\" fill=\"#fff\"><\/path><\/svg><\/button><\/div><div class=\"wp-block-ffl-blocks-gallery__content\">\n<p class=\"wp-block-paragraph\">So befindet sich das Land seit der im Januar 2012 im Norden Malis begonnenen Tuareg-Rebellion in einer echten sicherheitspolitischen und politischen Krise. Am 25. Juli 2013 z\u00e4hlten die Vereinten Nationen 342.033 Binnenvertriebene (IDPs). Seit Beginn der Krise hat sich die Ern\u00e4hrungssituation der Haushalte jedoch weiter verschlechtert. Eine der Hauptpriorit\u00e4ten war daher nicht nur die Eind\u00e4mmung der Nahrungsmittelkrise im Norden des Landes und die Verhinderung der Gefahr einer Hungersnot, sondern auch die Unterst\u00fctzung der Fl\u00fcchtlingsstr\u00f6me ins Ausland und der Binnenvertriebenen im S\u00fcden des Landes.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Von seinem lokalen Partner AP-FFL Mali alarmiert, engagiert sich FFL f\u00fcr die Unterst\u00fctzung von Fl\u00fcchtlingsfamilien in den Regionen S\u00e9gou, Mopti und Koulikoro, in denen die Entwicklungshilfeprojekte von FFL angesiedelt sind. Im Rahmen dieses humanit\u00e4ren Nothilfeprojekts f\u00fcr gef\u00e4hrdete Bev\u00f6lkerungsgruppen in Nordmali (URGEMALI) hat FFL beschlossen, dank seines vertrauten Partners vor Ort einer gezielten und begrenzten Verteilung Vorrang einzur\u00e4umen. Diese begrenzten und direkten Verteilungen stellen sicher, dass die Hilfe die Beg\u00fcnstigten direkt erreicht und Zwischenh\u00e4ndler vermieden werden. Ein Rahmen der Konsultation und Koordination mit lokalen und nationalen Beh\u00f6rden, lokalen NGOs und Gruppen, die Vertriebene aus dem Norden und malische Frauen vertreten, hat zur Identifizierung der am st\u00e4rksten gef\u00e4hrdeten Familien gef\u00fchrt. Ihre vorrangigen Bed\u00fcrfnisse und Ern\u00e4hrungspr\u00e4ferenzen wurden dann aufgelistet, um die am besten geeignete Hilfe zu leisten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8222;Wir f\u00fchlen uns manchmal wie Vieh behandelt&#8220;, sagten einige vertriebene Familien, wenn sie eine einheitliche Hilfsration f\u00fcr alle erhalten, nachdem sie in Reihen entwurzelter Menschen gewartet hatten. Hilfe in menschlichem Ma\u00dfstab ist nicht nur wirksamer, sondern erm\u00f6glicht es den Beg\u00fcnstigten auch, ihre W\u00fcrde und einen Anschein von Normalit\u00e4t in ihrem neuen, vor\u00fcbergehenden Leben zu bewahren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Gegensatz zu anderen Aufnahmest\u00e4dten im S\u00fcden Malis sind die vertriebenen Familien in S\u00e9gou nicht in Fl\u00fcchtlingslagern konzentriert, sondern bei Verwandten untergebracht. Diese \u00dcbergangssituation belastet auch die Ressourcen der Gastfamilien, die manchmal kaum die Mittel haben, das \u00dcberleben ihrer Familien zu sichern. Die von URGEMALI geleistete Hilfe entlastet daher den Druck auf diese Familien, deren Situation sich durch die \u00dcberschwemmungen der letzten Wochen, von denen mehr als 10.000 von ihnen betroffen waren, stark verschlechtert hat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der 19. August wurde zum allerersten Mal als Welttag der humanit\u00e4ren Hilfe begangen. Dieses Ereignis, das damals durch die internationalen Nachrichten vollauf gerechtfertigt war, war f\u00fcr alle eine Gelegenheit, sich [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[639],"tags":[540,557,593,891],"class_list":["post-3742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe-de","tag-fondation-follereau-de","tag-mali-de","tag-ong-de","tag-urgemali-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>URGEMALI - Fondation Follereau Luxembourg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"URGEMALI - Fondation Follereau Luxembourg\" \/>\n<meta property=\"og:description\" content=\"Der 19. August wurde zum allerersten Mal als Welttag der humanit\u00e4ren Hilfe begangen. Dieses Ereignis, das damals durch die internationalen Nachrichten vollauf gerechtfertigt war, war f\u00fcr alle eine Gelegenheit, sich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Follereau Luxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-09T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-26T13:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mark\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"mark\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/\"},\"author\":{\"name\":\"mark\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/ccaebb96539db056e9ae500a3add55dd\"},\"headline\":\"URGEMALI\",\"datePublished\":\"2013-09-09T00:00:00+00:00\",\"dateModified\":\"2020-06-26T13:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/\"},\"wordCount\":559,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/UrgeMali3.jpg\",\"keywords\":[\"Fondation Follereau\",\"Mali\",\"ONG\",\"Urgemali\"],\"articleSection\":[\"Non class\u00e9\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/\",\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/\",\"name\":\"URGEMALI - Fondation Follereau Luxembourg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/UrgeMali3.jpg\",\"datePublished\":\"2013-09-09T00:00:00+00:00\",\"dateModified\":\"2020-06-26T13:45:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/ccaebb96539db056e9ae500a3add55dd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/UrgeMali3.jpg\",\"contentUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/UrgeMali3.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2013\\\/09\\\/urgemali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ffl.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"URGEMALI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/\",\"name\":\"Fondation Follereau Luxembourg\",\"description\":\"Tout seul, on va vite. Ensemble, on va plus loin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ffl.lu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/ccaebb96539db056e9ae500a3add55dd\",\"name\":\"mark\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g\",\"caption\":\"mark\"},\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/author\\\/mark\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"URGEMALI - Fondation Follereau Luxembourg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/","og_locale":"de_DE","og_type":"article","og_title":"URGEMALI - Fondation Follereau Luxembourg","og_description":"Der 19. August wurde zum allerersten Mal als Welttag der humanit\u00e4ren Hilfe begangen. Dieses Ereignis, das damals durch die internationalen Nachrichten vollauf gerechtfertigt war, war f\u00fcr alle eine Gelegenheit, sich [&hellip;]","og_url":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/","og_site_name":"Fondation Follereau Luxembourg","article_published_time":"2013-09-09T00:00:00+00:00","article_modified_time":"2020-06-26T13:45:34+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg","type":"image\/jpeg"}],"author":"mark","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"mark","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/#article","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/"},"author":{"name":"mark","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/ccaebb96539db056e9ae500a3add55dd"},"headline":"URGEMALI","datePublished":"2013-09-09T00:00:00+00:00","dateModified":"2020-06-26T13:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/"},"wordCount":559,"commentCount":0,"image":{"@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg","keywords":["Fondation Follereau","Mali","ONG","Urgemali"],"articleSection":["Non class\u00e9"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/","url":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/","name":"URGEMALI - Fondation Follereau Luxembourg","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/#primaryimage"},"image":{"@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg","datePublished":"2013-09-09T00:00:00+00:00","dateModified":"2020-06-26T13:45:34+00:00","author":{"@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/ccaebb96539db056e9ae500a3add55dd"},"breadcrumb":{"@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/#primaryimage","url":"https:\/\/ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg","contentUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2013\/09\/UrgeMali3.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/ffl.lu\/de\/2013\/09\/urgemali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ffl.lu\/de\/"},{"@type":"ListItem","position":2,"name":"URGEMALI"}]},{"@type":"WebSite","@id":"https:\/\/ffl.lu\/de\/#website","url":"https:\/\/ffl.lu\/de\/","name":"Fondation Follereau Luxembourg","description":"Tout seul, on va vite. Ensemble, on va plus loin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ffl.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/ccaebb96539db056e9ae500a3add55dd","name":"mark","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g","caption":"mark"},"url":"https:\/\/ffl.lu\/de\/author\/mark\/"}]}},"_links":{"self":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/3742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/comments?post=3742"}],"version-history":[{"count":1,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/3742\/revisions"}],"predecessor-version":[{"id":3880,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/3742\/revisions\/3880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media\/2879"}],"wp:attachment":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media?parent=3742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/categories?post=3742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/tags?post=3742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}