{"id":3609,"date":"2019-11-14T00:00:00","date_gmt":"2019-11-14T00:00:00","guid":{"rendered":"https:\/\/www.ffl.lu\/2019\/11\/reduire-la-fracture-numerique\/"},"modified":"2020-06-29T08:50:09","modified_gmt":"2020-06-29T08:50:09","slug":"reduire-la-fracture-numerique","status":"publish","type":"post","link":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/","title":{"rendered":"\u00dcberbr\u00fcckung der digitalen Kluft"},"content":{"rendered":"<p><strong><em>Ziele 10 : Verringerung der Ungleichheiten innerhalb und zwischen den L\u00e4ndern.<\/em><\/strong><\/p>\n<p>Technologien sind in allen Bereichen menschlicher Aktivit\u00e4ten pr\u00e4sent. Unter ihnen stellen der Computer und das Internet ein privilegiertes Mittel zum Lehren und Lernen dar. Der Zugang zu diesen Instrumenten erm\u00f6glicht es insbesondere, die allgemeine und berufliche Bildung, die Alphabetisierung und die Besch\u00e4ftigungsf\u00e4higkeit f\u00fcr alle zu verbessern.<\/p>\n<p>Im Jahr 2011 startete die Stiftung das Projekt &#8222;Mind The Gap&#8220; in Mali, Benin und Togo mit dem Ziel, die digitale Kluft zwischen den Bev\u00f6lkerungen des Nordens und des S\u00fcdens zu verringern. Diese Kluft beraubt einen ganzen Teil der Bev\u00f6lkerung der M\u00f6glichkeit, Zugang zu Informationen, Wissen und Netzwerken zu haben und von den gro\u00dfen Entwicklungskapazit\u00e4ten zu profitieren, die die IKT bieten. Viele junge Menschen haben aufgrund mangelnder Ausstattung nicht die M\u00f6glichkeit, praktische Computerkurse zu erhalten, obwohl diese im Lehrplan der Schulen vorgesehen sind.<\/p>\n<p>Um hier Abhilfe zu schaffen, sammelt die Stiftung Computer und Computerzubeh\u00f6r bei luxemburgischen Unternehmen und schickt sie an ihre Partner. Seit 2011 wurden bereits mehr als 3.200 Computer in 280 Schulen installiert, wodurch 40.000 Kinder ausgebildet werden konnten.<\/p>\n<p><strong>Wir danken den gro\u00dfz\u00fcgigen Unternehmen, die sich f\u00fcr dieses Projekt im Jahr 2019 engagieren, insbesondere der EBRC f\u00fcr ihre gro\u00dfz\u00fcgige Spende von 250 Mikrocomputern, die an diesem Freitag, dem 8. November 2019, get\u00e4tigt wurde und nach Togo gehen wird. Im Jahr 2010 war EBRC eines der ersten luxemburgischen Unternehmen, das das ESR-Label erhielt. &#8222;Unsere CSR-Politik ist etwas, das wir t\u00e4glich in der Gesellschaft erleben. &#8222;Sandrine Boucquey, Direktorin HR &amp; Recht<\/strong><\/p>\n<p>&#8211;<\/p>\n<p><em>Die Stiftung dankt auch Computrade, Encevo, Le Foyer, Creos, Soci\u00e9t\u00e9 G\u00e9n\u00e9rale, Banque et Caisse d&#8217;Epargne de l&#8217;Etat und Streff, insbesondere Anne-Marie de Hoef, die es erm\u00f6glicht haben, dieses Projekt f\u00fcr Tausende von Studenten im Jahr 2019 umzusetzen.<\/em><\/p>\n<p><em>Es gibt verschiedene Formen der Partnerschaft, um sich als Unternehmen zu engagieren: Sponsoring von Kompetenzen, in Form von Sachleistungen, technologisch, finanziell&#8230;\u00a0 Mind the Gap ist eine Form der technologischen, aber auch der finanziellen F\u00f6rderung. \u00dcber die Sammlung des Materials hinaus sind mit der Lagerung und dem Versand des Materials in der Tat Kosten verbunden. Das Budget pro Land betr\u00e4gt 15.000\u20ac. F\u00fcr weitere Informationen z\u00f6gern Sie nicht, sich an die Stiftung zu wenden: presse@ffl.lu<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ziele 10 : Verringerung der Ungleichheiten innerhalb und zwischen den L\u00e4ndern. Technologien sind in allen Bereichen menschlicher Aktivit\u00e4ten pr\u00e4sent. Unter ihnen stellen der Computer und das Internet ein privilegiertes Mittel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2380,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[610],"tags":[1003,540,600],"class_list":["post-3609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spenden-de","tag-ebrc","tag-fondation-follereau-de","tag-mind-the-gap-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcberbr\u00fcckung der digitalen Kluft - Fondation Follereau Luxembourg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberbr\u00fcckung der digitalen Kluft - Fondation Follereau Luxembourg\" \/>\n<meta property=\"og:description\" content=\"Ziele 10 : Verringerung der Ungleichheiten innerhalb und zwischen den L\u00e4ndern. Technologien sind in allen Bereichen menschlicher Aktivit\u00e4ten pr\u00e4sent. Unter ihnen stellen der Computer und das Internet ein privilegiertes Mittel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Follereau Luxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-14T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-29T08:50:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ffl.lu\/wp-content\/uploads\/2020\/04\/20191108-EBRC-Mind-The-Gap-1web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4639\" \/>\n\t<meta property=\"og:image:height\" content=\"3092\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mark\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"mark\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/\"},\"author\":{\"name\":\"mark\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/ccaebb96539db056e9ae500a3add55dd\"},\"headline\":\"\u00dcberbr\u00fcckung der digitalen Kluft\",\"datePublished\":\"2019-11-14T00:00:00+00:00\",\"dateModified\":\"2020-06-29T08:50:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/\"},\"wordCount\":386,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20191108-EBRC-Mind-The-Gap-1web.jpg\",\"keywords\":[\"EBRC\",\"Fondation Follereau\",\"Mind The Gap\"],\"articleSection\":[\"Spenden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/\",\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/\",\"name\":\"\u00dcberbr\u00fcckung der digitalen Kluft - Fondation Follereau Luxembourg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20191108-EBRC-Mind-The-Gap-1web.jpg\",\"datePublished\":\"2019-11-14T00:00:00+00:00\",\"dateModified\":\"2020-06-29T08:50:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/ccaebb96539db056e9ae500a3add55dd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20191108-EBRC-Mind-The-Gap-1web.jpg\",\"contentUrl\":\"https:\\\/\\\/ffl.lu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20191108-EBRC-Mind-The-Gap-1web.jpg\",\"width\":4639,\"height\":3092},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/2019\\\/11\\\/reduire-la-fracture-numerique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ffl.lu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcberbr\u00fcckung der digitalen Kluft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/\",\"name\":\"Fondation Follereau Luxembourg\",\"description\":\"Tout seul, on va vite. Ensemble, on va plus loin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ffl.lu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ffl.lu\\\/de\\\/#\\\/schema\\\/person\\\/ccaebb96539db056e9ae500a3add55dd\",\"name\":\"mark\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g\",\"caption\":\"mark\"},\"url\":\"https:\\\/\\\/ffl.lu\\\/de\\\/author\\\/mark\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberbr\u00fcckung der digitalen Kluft - Fondation Follereau Luxembourg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcberbr\u00fcckung der digitalen Kluft - Fondation Follereau Luxembourg","og_description":"Ziele 10 : Verringerung der Ungleichheiten innerhalb und zwischen den L\u00e4ndern. Technologien sind in allen Bereichen menschlicher Aktivit\u00e4ten pr\u00e4sent. Unter ihnen stellen der Computer und das Internet ein privilegiertes Mittel [&hellip;]","og_url":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/","og_site_name":"Fondation Follereau Luxembourg","article_published_time":"2019-11-14T00:00:00+00:00","article_modified_time":"2020-06-29T08:50:09+00:00","og_image":[{"width":4639,"height":3092,"url":"https:\/\/ffl.lu\/wp-content\/uploads\/2020\/04\/20191108-EBRC-Mind-The-Gap-1web.jpg","type":"image\/jpeg"}],"author":"mark","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"mark","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/#article","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/"},"author":{"name":"mark","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/ccaebb96539db056e9ae500a3add55dd"},"headline":"\u00dcberbr\u00fcckung der digitalen Kluft","datePublished":"2019-11-14T00:00:00+00:00","dateModified":"2020-06-29T08:50:09+00:00","mainEntityOfPage":{"@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/"},"wordCount":386,"commentCount":0,"image":{"@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2020\/04\/20191108-EBRC-Mind-The-Gap-1web.jpg","keywords":["EBRC","Fondation Follereau","Mind The Gap"],"articleSection":["Spenden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/","url":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/","name":"\u00dcberbr\u00fcckung der digitalen Kluft - Fondation Follereau Luxembourg","isPartOf":{"@id":"https:\/\/ffl.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/#primaryimage"},"image":{"@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/#primaryimage"},"thumbnailUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2020\/04\/20191108-EBRC-Mind-The-Gap-1web.jpg","datePublished":"2019-11-14T00:00:00+00:00","dateModified":"2020-06-29T08:50:09+00:00","author":{"@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/ccaebb96539db056e9ae500a3add55dd"},"breadcrumb":{"@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/#primaryimage","url":"https:\/\/ffl.lu\/wp-content\/uploads\/2020\/04\/20191108-EBRC-Mind-The-Gap-1web.jpg","contentUrl":"https:\/\/ffl.lu\/wp-content\/uploads\/2020\/04\/20191108-EBRC-Mind-The-Gap-1web.jpg","width":4639,"height":3092},{"@type":"BreadcrumbList","@id":"https:\/\/ffl.lu\/de\/2019\/11\/reduire-la-fracture-numerique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ffl.lu\/de\/"},{"@type":"ListItem","position":2,"name":"\u00dcberbr\u00fcckung der digitalen Kluft"}]},{"@type":"WebSite","@id":"https:\/\/ffl.lu\/de\/#website","url":"https:\/\/ffl.lu\/de\/","name":"Fondation Follereau Luxembourg","description":"Tout seul, on va vite. Ensemble, on va plus loin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ffl.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/ffl.lu\/de\/#\/schema\/person\/ccaebb96539db056e9ae500a3add55dd","name":"mark","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce96f9eedffc79eab8c7d97078b476a4df2ed3579c296fed4e23db8a1c05703c?s=96&d=mm&r=g","caption":"mark"},"url":"https:\/\/ffl.lu\/de\/author\/mark\/"}]}},"_links":{"self":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/3609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/comments?post=3609"}],"version-history":[{"count":1,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/3609\/revisions"}],"predecessor-version":[{"id":3917,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/posts\/3609\/revisions\/3917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media\/2380"}],"wp:attachment":[{"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/media?parent=3609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/categories?post=3609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ffl.lu\/de\/wp-json\/wp\/v2\/tags?post=3609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}